{"id":3389,"date":"2022-04-03T08:22:00","date_gmt":"2022-04-03T06:22:00","guid":{"rendered":"https:\/\/feuerwehrwoerth.de\/?post_type=einsatz&#038;p=3389"},"modified":"2022-04-04T15:49:48","modified_gmt":"2022-04-04T13:49:48","slug":"unterstuetzung-rettungsdienst-mit-dlk","status":"publish","type":"einsatz","link":"https:\/\/feuerwehrwoerth.de\/index.php\/einsatzberichte\/unterstuetzung-rettungsdienst-mit-dlk\/","title":{"rendered":"Unterst\u00fctzung Rettungsdienst"},"content":{"rendered":"\n<p>Wir wurden zur Unterst\u00fctzung des Rettungsdienstes gerufen. Zur patientengerechten Rettung musste die Drehleiter eingesetzt werden.<\/p>\n","protected":false},"author":2,"featured_media":2990,"template":"","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","ngg_post_thumbnail":0,"einsatz_weight":1,"footnotes":""},"categories":[],"einsatzart":[5],"fahrzeug":[16,17,48],"exteinsatzmittel":[9,10],"alarmierungsart":[],"evw_unit":[43],"class_list":["post-3389","einsatz","type-einsatz","status-publish","has-post-thumbnail","hentry","einsatzart-technische-hilfeleistung","fahrzeug-hlf-10-10","fahrzeug-dlk-23-12","fahrzeug-fez","exteinsatzmittel-polizei","exteinsatzmittel-rettungsdienst","evw_unit-woerth-am-rhein"],"featured_img":"https:\/\/feuerwehrwoerth.de\/wp-content\/uploads\/2022\/01\/dlk-frontseite.jpg","coauthors":[],"author_meta":{"author_link":"https:\/\/feuerwehrwoerth.de\/index.php\/author\/tobias\/","display_name":"Tobias"},"relative_dates":{"created":"Posted 4\u00a0Jahren ago","modified":"Updated 4\u00a0Jahren ago"},"absolute_dates":{"created":"Posted on 3. April 2022","modified":"Updated on 4. April 2022"},"absolute_dates_time":{"created":"Posted on 3. April 2022 8:22","modified":"Updated on 4. April 2022 15:49"},"featured_img_caption":"","tax_additional":{"category":{"linked":[],"unlinked":[],"slug":"category","name":"Kategorien"},"einsatzart":{"linked":["<a href=\"https:\/\/feuerwehrwoerth.de\/index.php\/einsatzart\/technische-hilfeleistung\/\" class=\"advgb-post-tax-term\">Technische Hilfeleistung<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Technische Hilfeleistung<\/span>"],"slug":"einsatzart","name":"Einsatzarten"},"fahrzeug":{"linked":["<a href=\"https:\/\/feuerwehrwoerth.de\/index.php\/fahrzeug\/hlf-10-10\/\" class=\"advgb-post-tax-term\">1\/45 (HLF 10\/10)<\/a>","<a href=\"https:\/\/feuerwehrwoerth.de\/index.php\/fahrzeug\/dlk-23-12\/\" class=\"advgb-post-tax-term\">1\/34 (DL(A)K 23\/12)<\/a>","<a href=\"https:\/\/feuerwehrwoerth.de\/index.php\/fahrzeug\/fez\/\" class=\"advgb-post-tax-term\">FEZ<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">1\/45 (HLF 10\/10)<\/span>","<span class=\"advgb-post-tax-term\">1\/34 (DL(A)K 23\/12)<\/span>","<span class=\"advgb-post-tax-term\">FEZ<\/span>"],"slug":"fahrzeug","name":"Fahrzeuge"},"exteinsatzmittel":{"linked":["<a href=\"https:\/\/feuerwehrwoerth.de\/index.php\/externe-einsatzmittel\/polizei\/\" class=\"advgb-post-tax-term\">Polizei<\/a>","<a href=\"https:\/\/feuerwehrwoerth.de\/index.php\/externe-einsatzmittel\/rettungsdienst\/\" class=\"advgb-post-tax-term\">Rettungsdienst<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Polizei<\/span>","<span class=\"advgb-post-tax-term\">Rettungsdienst<\/span>"],"slug":"exteinsatzmittel","name":"Externe Einsatzmittel"},"alarmierungsart":{"linked":[],"unlinked":[],"slug":"alarmierungsart","name":"Alarmierungsarten"},"evw_unit":{"linked":["<a href=\"https:\/\/feuerwehrwoerth.de\/index.php\/evw_unit\/woerth-am-rhein\/\" class=\"advgb-post-tax-term\">W\u00f6rth<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">W\u00f6rth<\/span>"],"slug":"evw_unit","name":"Einheiten"}},"series_order":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/einsatz\/3389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/einsatz"}],"about":[{"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/types\/einsatz"}],"author":[{"embeddable":true,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":2,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/einsatz\/3389\/revisions"}],"predecessor-version":[{"id":3391,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/einsatz\/3389\/revisions\/3391"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/media\/2990"}],"wp:attachment":[{"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/media?parent=3389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/categories?post=3389"},{"taxonomy":"einsatzart","embeddable":true,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/einsatzart?post=3389"},{"taxonomy":"fahrzeug","embeddable":true,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/fahrzeug?post=3389"},{"taxonomy":"exteinsatzmittel","embeddable":true,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/exteinsatzmittel?post=3389"},{"taxonomy":"alarmierungsart","embeddable":true,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/alarmierungsart?post=3389"},{"taxonomy":"evw_unit","embeddable":true,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/evw_unit?post=3389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}