{"id":4392,"date":"2022-12-03T19:39:00","date_gmt":"2022-12-03T18:39:00","guid":{"rendered":"https:\/\/feuerwehrwoerth.de\/?post_type=einsatz&#038;p=4392"},"modified":"2023-01-01T20:16:52","modified_gmt":"2023-01-01T19:16:52","slug":"notfalltueroeffnung-17","status":"publish","type":"einsatz","link":"https:\/\/feuerwehrwoerth.de\/index.php\/einsatzberichte\/notfalltueroeffnung-17\/","title":{"rendered":"Notfallt\u00fcr\u00f6ffnung"},"content":{"rendered":"\n<p>Wir wurden zu einer Notfallt\u00fcr\u00f6ffnung alarmiert.<\/p>\n","protected":false},"author":2,"featured_media":2877,"template":"","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","ngg_post_thumbnail":0,"einsatz_weight":1,"footnotes":""},"categories":[],"einsatzart":[5],"fahrzeug":[16,18,48],"exteinsatzmittel":[9,10],"alarmierungsart":[],"evw_unit":[43],"class_list":["post-4392","einsatz","type-einsatz","status-publish","has-post-thumbnail","hentry","einsatzart-technische-hilfeleistung","fahrzeug-hlf-10-10","fahrzeug-mtf","fahrzeug-fez","exteinsatzmittel-polizei","exteinsatzmittel-rettungsdienst","evw_unit-woerth-am-rhein"],"featured_img":"https:\/\/feuerwehrwoerth.de\/wp-content\/uploads\/2022\/01\/tueroeffnung_artikelbild-e1681295436454.jpg","coauthors":[],"author_meta":{"author_link":"https:\/\/feuerwehrwoerth.de\/index.php\/author\/tobias\/","display_name":"Tobias"},"relative_dates":{"created":"Posted 3\u00a0Jahren ago","modified":"Updated 3\u00a0Jahren ago"},"absolute_dates":{"created":"Posted on 3. Dezember 2022","modified":"Updated on 1. Januar 2023"},"absolute_dates_time":{"created":"Posted on 3. Dezember 2022 19:39","modified":"Updated on 1. Januar 2023 20:16"},"featured_img_caption":"","tax_additional":{"category":{"linked":[],"unlinked":[],"slug":"category","name":"Kategorien"},"einsatzart":{"linked":["<a href=\"https:\/\/feuerwehrwoerth.de\/index.php\/einsatzart\/technische-hilfeleistung\/\" class=\"advgb-post-tax-term\">Technische Hilfeleistung<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Technische Hilfeleistung<\/span>"],"slug":"einsatzart","name":"Einsatzarten"},"fahrzeug":{"linked":["<a href=\"https:\/\/feuerwehrwoerth.de\/index.php\/fahrzeug\/hlf-10-10\/\" class=\"advgb-post-tax-term\">1\/45 (HLF 10\/10)<\/a>","<a href=\"https:\/\/feuerwehrwoerth.de\/index.php\/fahrzeug\/mtf\/\" class=\"advgb-post-tax-term\">1\/19 (MTF)<\/a>","<a href=\"https:\/\/feuerwehrwoerth.de\/index.php\/fahrzeug\/fez\/\" class=\"advgb-post-tax-term\">FEZ<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">1\/45 (HLF 10\/10)<\/span>","<span class=\"advgb-post-tax-term\">1\/19 (MTF)<\/span>","<span class=\"advgb-post-tax-term\">FEZ<\/span>"],"slug":"fahrzeug","name":"Fahrzeuge"},"exteinsatzmittel":{"linked":["<a href=\"https:\/\/feuerwehrwoerth.de\/index.php\/externe-einsatzmittel\/polizei\/\" class=\"advgb-post-tax-term\">Polizei<\/a>","<a href=\"https:\/\/feuerwehrwoerth.de\/index.php\/externe-einsatzmittel\/rettungsdienst\/\" class=\"advgb-post-tax-term\">Rettungsdienst<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Polizei<\/span>","<span class=\"advgb-post-tax-term\">Rettungsdienst<\/span>"],"slug":"exteinsatzmittel","name":"Externe Einsatzmittel"},"alarmierungsart":{"linked":[],"unlinked":[],"slug":"alarmierungsart","name":"Alarmierungsarten"},"evw_unit":{"linked":["<a href=\"https:\/\/feuerwehrwoerth.de\/index.php\/evw_unit\/woerth-am-rhein\/\" class=\"advgb-post-tax-term\">W\u00f6rth<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">W\u00f6rth<\/span>"],"slug":"evw_unit","name":"Einheiten"}},"series_order":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/einsatz\/4392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/einsatz"}],"about":[{"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/types\/einsatz"}],"author":[{"embeddable":true,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/einsatz\/4392\/revisions"}],"predecessor-version":[{"id":4393,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/einsatz\/4392\/revisions\/4393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/media\/2877"}],"wp:attachment":[{"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/media?parent=4392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/categories?post=4392"},{"taxonomy":"einsatzart","embeddable":true,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/einsatzart?post=4392"},{"taxonomy":"fahrzeug","embeddable":true,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/fahrzeug?post=4392"},{"taxonomy":"exteinsatzmittel","embeddable":true,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/exteinsatzmittel?post=4392"},{"taxonomy":"alarmierungsart","embeddable":true,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/alarmierungsart?post=4392"},{"taxonomy":"evw_unit","embeddable":true,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/evw_unit?post=4392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}