{"id":6242,"date":"2024-08-19T19:18:00","date_gmt":"2024-08-19T17:18:00","guid":{"rendered":"https:\/\/feuerwehrwoerth.de\/?post_type=einsatz&#038;p=6242"},"modified":"2024-08-21T16:54:34","modified_gmt":"2024-08-21T14:54:34","slug":"personensuche-7","status":"publish","type":"einsatz","link":"https:\/\/feuerwehrwoerth.de\/index.php\/einsatzberichte\/personensuche-7\/","title":{"rendered":"Personensuche"},"content":{"rendered":"\n<p>Unsere Drohneneinheit wurde zur Unterst\u00fctzung der Feuerwehr Bellheim bei einer Personensuche alarmiert. Es wurden mehrere Suchgebiete mit der Drohne abgeflogen. Die W\u00e4rmebildkamera unserer Drohnen erkennt bereits kleine Temperaturunterschiede. Deshalb ist diese auch f\u00fcr die Suche in der Nacht geeignet. Gegen 23 Uhr wurden die Suchma\u00dfnahmen ergebnislos\u00a0abgebrochen. Die Suche wurde am Folgetag fortgesetzt.<\/p>\n","protected":false},"author":2,"featured_media":4050,"template":"","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","ngg_post_thumbnail":0,"einsatz_weight":1,"footnotes":""},"categories":[],"einsatzart":[5],"fahrzeug":[48,81,114],"exteinsatzmittel":[9,10,179,180],"alarmierungsart":[],"evw_unit":[43],"class_list":["post-6242","einsatz","type-einsatz","status-publish","has-post-thumbnail","hentry","einsatzart-technische-hilfeleistung","fahrzeug-fez","fahrzeug-mzf-woerth","fahrzeug-einsatzdrohne","exteinsatzmittel-polizei","exteinsatzmittel-rettungsdienst","exteinsatzmittel-feuerwehr-vg-bellheim","exteinsatzmittel-facheinheit-drohne-des-lk-ger","evw_unit-woerth-am-rhein"],"featured_img":"https:\/\/feuerwehrwoerth.de\/wp-content\/uploads\/2022\/09\/personensuche-drohne-artikelbild-e1681294456722.jpg","coauthors":[],"author_meta":{"author_link":"https:\/\/feuerwehrwoerth.de\/index.php\/author\/tobias\/","display_name":"Tobias"},"relative_dates":{"created":"Posted 2\u00a0Jahren ago","modified":"Updated 2\u00a0Jahren ago"},"absolute_dates":{"created":"Posted on 19. August 2024","modified":"Updated on 21. August 2024"},"absolute_dates_time":{"created":"Posted on 19. August 2024 19:18","modified":"Updated on 21. August 2024 16:54"},"featured_img_caption":"0.9.142","tax_additional":{"category":{"linked":[],"unlinked":[],"slug":"category","name":"Kategorien"},"einsatzart":{"linked":["<a href=\"https:\/\/feuerwehrwoerth.de\/index.php\/einsatzart\/technische-hilfeleistung\/\" class=\"advgb-post-tax-term\">Technische Hilfeleistung<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Technische Hilfeleistung<\/span>"],"slug":"einsatzart","name":"Einsatzarten"},"fahrzeug":{"linked":["<a href=\"https:\/\/feuerwehrwoerth.de\/index.php\/fahrzeug\/fez\/\" class=\"advgb-post-tax-term\">FEZ<\/a>","<a href=\"https:\/\/feuerwehrwoerth.de\/index.php\/fahrzeug\/mzf-woerth\/\" class=\"advgb-post-tax-term\">1\/71 (MZF 1)<\/a>","<a href=\"https:\/\/feuerwehrwoerth.de\/index.php\/fahrzeug\/einsatzdrohne\/\" class=\"advgb-post-tax-term\">Einsatzdrohne<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">FEZ<\/span>","<span class=\"advgb-post-tax-term\">1\/71 (MZF 1)<\/span>","<span class=\"advgb-post-tax-term\">Einsatzdrohne<\/span>"],"slug":"fahrzeug","name":"Fahrzeuge"},"exteinsatzmittel":{"linked":["<a href=\"https:\/\/feuerwehrwoerth.de\/index.php\/externe-einsatzmittel\/polizei\/\" class=\"advgb-post-tax-term\">Polizei<\/a>","<a href=\"https:\/\/feuerwehrwoerth.de\/index.php\/externe-einsatzmittel\/rettungsdienst\/\" class=\"advgb-post-tax-term\">Rettungsdienst<\/a>","<a href=\"https:\/\/feuerwehrwoerth.de\/index.php\/externe-einsatzmittel\/feuerwehr-vg-bellheim\/\" class=\"advgb-post-tax-term\">Feuerwehr VG Bellheim<\/a>","<a href=\"https:\/\/feuerwehrwoerth.de\/index.php\/externe-einsatzmittel\/facheinheit-drohne-des-lk-ger\/\" class=\"advgb-post-tax-term\">Facheinheit Drohne des LK GER<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Polizei<\/span>","<span class=\"advgb-post-tax-term\">Rettungsdienst<\/span>","<span class=\"advgb-post-tax-term\">Feuerwehr VG Bellheim<\/span>","<span class=\"advgb-post-tax-term\">Facheinheit Drohne des LK GER<\/span>"],"slug":"exteinsatzmittel","name":"Externe Einsatzmittel"},"alarmierungsart":{"linked":[],"unlinked":[],"slug":"alarmierungsart","name":"Alarmierungsarten"},"evw_unit":{"linked":["<a href=\"https:\/\/feuerwehrwoerth.de\/index.php\/evw_unit\/woerth-am-rhein\/\" class=\"advgb-post-tax-term\">W\u00f6rth<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">W\u00f6rth<\/span>"],"slug":"evw_unit","name":"Einheiten"}},"series_order":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/einsatz\/6242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/einsatz"}],"about":[{"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/types\/einsatz"}],"author":[{"embeddable":true,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/einsatz\/6242\/revisions"}],"predecessor-version":[{"id":6243,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/einsatz\/6242\/revisions\/6243"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/media\/4050"}],"wp:attachment":[{"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/media?parent=6242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/categories?post=6242"},{"taxonomy":"einsatzart","embeddable":true,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/einsatzart?post=6242"},{"taxonomy":"fahrzeug","embeddable":true,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/fahrzeug?post=6242"},{"taxonomy":"exteinsatzmittel","embeddable":true,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/exteinsatzmittel?post=6242"},{"taxonomy":"alarmierungsart","embeddable":true,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/alarmierungsart?post=6242"},{"taxonomy":"evw_unit","embeddable":true,"href":"https:\/\/feuerwehrwoerth.de\/index.php\/wp-json\/wp\/v2\/evw_unit?post=6242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}